{"id":247,"date":"2010-03-19T11:31:56","date_gmt":"2010-03-19T10:31:56","guid":{"rendered":"http:\/\/www.buscounviaje.com\/blog\/?p=247"},"modified":"2019-09-09T18:07:17","modified_gmt":"2019-09-09T16:07:17","slug":"empezamos-el-viaje-del-blog","status":"publish","type":"post","link":"https:\/\/www.buscounviaje.com\/blog\/noticias-buv\/empezamos-el-viaje-del-blog\/","title":{"rendered":"\u00a1Empezamos el blog de viajes de BuscoUnViaje!"},"content":{"rendered":"\n<p>Despu\u00e9s de un silencio de varias semanas (provocado por lo divertidos que son los <a href=\"https:\/\/www.buscounviaje.com\/blog\/noticias-buv\/de-como-una-idea-y-una-lumbalgia-se-convirtieron-en-una-empresa-web-buscounviaje-com\/\">comienzos de una empresa<\/a>), queremos anunciar que a partir de la semana que viene <strong>el blog de BuscoUnViaje.com se pone en marcha<\/strong>. Y como es de bien educado ser presentado, empezamos por hacer una breve descripci\u00f3n de cada uno de los &#8216;autores&#8217; que van a escribir en este blog.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>JR<\/strong> es garant\u00eda de una cosa para este blog: va a hablar de escalada tanto como le dejemos. Y como aqu\u00ed hay mucha libertad, calculamos que en el 95% de sus entradas aparecer\u00e1 la palabra &#8216;roca&#8217;.<\/li><li><strong>La Tiradora de hilos<\/strong>, la m\u00e1s so\u00f1adora de los autores, aportar\u00e1 ese toque espiritual y de felicidad con el que todo el mundo deber\u00eda despertarse cada ma\u00f1ana.<\/li><li><strong>Miguel<\/strong>, el benjam\u00edn del equipo de autores, nos har\u00e1 sufrir cont\u00e1ndonos todas esas cosas que \u00e9l a\u00fan hace y nosotros ya hemos olvidado (por culpa de lumbalgias, rodillas, contracturas, &#8230;)<\/li><li><strong>Alberto<\/strong>, el hombre minucioso, nos ayudar\u00e1 entre otras cosas a planificar mejor nuestros viajes al mismo tiempo que gastamos poco dinero por la m\u00e1xima calidad.<\/li><li><strong>Ra y Mon<\/strong> s\u00f3lo promete una cosa, que intentar\u00e1 no superar jam\u00e1s la longitud de la entrada donde narr\u00f3 la creaci\u00f3n de <a href=\"https:\/\/www.buscounviaje.com\">BuscoUnViaje.com<\/a>. Hubo varios a los que les sali\u00f3 barba ley\u00e9ndolo&#8230;<\/li><li><strong>Tullonia<\/strong>: tambi\u00e9n conocida como <a href=\"http:\/\/hoycocinamama.blogspot.com\" target=\"_blank\" rel=\"nofollow\">mam\u00e1<\/a>, compartir\u00e1 con nosotros recetas de todo el mundo. No esper\u00e9is sofisticaci\u00f3n, lo importante para Tullonia es que todos comamos mejor.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"http:\/\/www.buscounviaje.com\/blog\/wp-content\/uploads\/2010\/03\/teclado_mano_mapa-439x292.jpg\" alt=\"Escribamos sobre viajes\" class=\"wp-image-253\"\/><\/figure><\/div>\n\n\n\n<p><br>En este blog vamos a hablar un poco de todo, pero siempre centrado en el mundo del viaje y desde la \u00f3ptica personal de cada uno de los autores. Unos somos m\u00e1s c\u00ednicos, otros m\u00e1s pr\u00e1cticos, algunos m\u00e1s poetas y varios muy despistados. Para intentar poner un poco de orden y que las cosas no se vayan de las manos, hemos creado 7 categor\u00edas a las que intentaremos ce\u00f1irnos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Bien vale un viaje<\/strong>: actividades, lugares, personas, museos, espect\u00e1culos, &#8230; que justifican por s\u00ed mismos un viaje. La secci\u00f3n m\u00e1s propensa a las sorpresas&#8230;<\/li><li><strong>Consejos de viaje: <\/strong>para compartir todos esos trucos y consejos que hacen m\u00e1s f\u00e1cil viajar. Algunos somos muy mani\u00e1ticos, as\u00ed que algunos consejos podr\u00e1n sonaros surrealistas (como lo de impregnar con permetrina toda la ropa antes de un viaje a un lugar con malaria).<\/li><li><strong>Degustado en un viaje: <\/strong>las recetas del mundo de Tullonia. Existe la posibilidad de que otros autores hagan incursiones en esta secci\u00f3n&#8230; pero si aprecias tu est\u00f3mago, mejor no les hagas caso.<strong><br><\/strong><\/li><li><strong>Gente viaje: <\/strong>el objetivo es acercaros a trav\u00e9s de entrevistas a gente interesante y que haya viajado. Si alguien quiere postularse como candidato (o conoce al viajero perfecto), puede <a href=\"https:\/\/www.buscounviaje.com\/contacto\/\">contactarnos aqu\u00ed.<\/a><\/li><li><strong>Libros de viaje: <\/strong>somos viajeros, pero antes de nada fuimos lectores. Aqu\u00ed rese\u00f1aremos, cada uno a nuestra manera, esos libros relacionados con el viaje que merecen la pena.<\/li><li><strong>Visto en un viaje: <\/strong>muchas veces planificamos un viaje a un destino simplemente porque vimos una foto que nos impact\u00f3 de ese lugar. Esta secci\u00f3n es para eso, para impactaros visualmente.<\/li><li><strong>Vivido en un viaje: <\/strong>la secci\u00f3n donde m\u00e1s peligro tenemos algunos, los relatos de nuestros viajes. Prometemos que si alguno se pasa de l\u00edneas le dejaremos sin postre.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"http:\/\/www.buscounviaje.com\/blog\/wp-content\/uploads\/2010\/03\/Picture-2.png\" alt=\"\" class=\"wp-image-254\"\/><\/figure><\/div>\n\n\n\n<p><strong><\/strong><br>Preparados, listos, &#8230;. \u00a1ya! El lunes, JR re-romper\u00e1 el silencio del blog cont\u00e1ndonos &#8216;algo&#8217; sobre un libro de viajes. Se admiten apuestas&#8230; \u00bfser\u00e1 un libro de viajes de escalada?<\/p>\n\n\n\n<p>*En 2019 decidimos realizar un reestructuraci\u00f3n del contenido del blog, por lo que algunas categor\u00edas pueden haber cambiado. \u00a1El esp\u00edritu es el mismo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de un silencio de varias semanas (provocado por lo divertidos que son los comienzos de una empresa), queremos anunciar que a partir de la semana que viene el blog de BuscoUnViaje.com se pone en marcha. Y como es de bien educado ser presentado, empezamos por hacer una breve descripci\u00f3n de cada uno de los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[246,484],"class_list":{"0":"post-247","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-buv","8":"tag-equipo-buscounviaje","9":"tag-noticias"},"aioseo_notices":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.buscounviaje.com\/blog\/wp-json\/wp\/v2\/posts\/247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buscounviaje.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buscounviaje.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buscounviaje.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buscounviaje.com\/blog\/wp-json\/wp\/v2\/comments?post=247"}],"version-history":[{"count":2,"href":"https:\/\/www.buscounviaje.com\/blog\/wp-json\/wp\/v2\/posts\/247\/revisions"}],"predecessor-version":[{"id":10985,"href":"https:\/\/www.buscounviaje.com\/blog\/wp-json\/wp\/v2\/posts\/247\/revisions\/10985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buscounviaje.com\/blog\/wp-json\/wp\/v2\/media\/10984"}],"wp:attachment":[{"href":"https:\/\/www.buscounviaje.com\/blog\/wp-json\/wp\/v2\/media?parent=247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buscounviaje.com\/blog\/wp-json\/wp\/v2\/categories?post=247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buscounviaje.com\/blog\/wp-json\/wp\/v2\/tags?post=247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}